{"id":3202,"date":"2024-11-07T18:36:50","date_gmt":"2024-11-07T18:36:50","guid":{"rendered":"https:\/\/aykasa.com\/inicio\/"},"modified":"2025-12-16T06:38:43","modified_gmt":"2025-12-16T06:38:43","slug":"inicio","status":"publish","type":"page","link":"https:\/\/aykasa.com\/es\/","title":{"rendered":"Inicio"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-d843ef95 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4fbe4bca alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-6b3aacba uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\"><strong>Cajas Plegables<\/strong><\/h2><\/div><p class=\"uagb-ifb-desc\">\u00a1Desaf\u00eda los l\u00edmites de tu imaginaci\u00f3n con las cajas originales de Aykasa! Estanter\u00edas, contenedores para juguetes, vestidores y mucho m\u00e1s\u2026 Soluciones pr\u00e1cticas para cada rinc\u00f3n de tu hogar te esperan.<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-53b8e0b5\">\n<div class=\"wp-block-uagb-info-box uagb-block-12c941e8 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/aykasa.com\/es\/?post_type=product&#038;p=3541\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_blank\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2024\/11\/430x519-maxi.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Caja Maxi<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-c4b23950 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/aykasa.com\/es\/product\/caja-midi-40x30x14\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2024\/11\/430x519-midi.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Caja Midi<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-a81b71dd uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/aykasa.com\/es\/product\/mini-caja-266-x171-x105\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2024\/11\/430x519-mini.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Caja Mini<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-40367a60 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-31c1363d uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Tapas<\/h2><\/div><p class=\"uagb-ifb-desc\">Inspiradas en la solidez de las estructuras de panal de abeja, las tapas Aykasa ofrecen una combinaci\u00f3n perfecta de ligereza y resistencia.<br>Disponibles en colores transparente y coco, estas tapas combinan f\u00e1cilmente con todos los colores Aykasa.<br>Puede utilizarlas para proteger sus objetos, apilarlos de forma segura o convertir su caja en una mesa o estanter\u00eda.<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-e3d65400\">\n<div class=\"wp-block-uagb-info-box uagb-block-63831036 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/aykasa.com\/es\/product\/tapas-maxi-605-x-405\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_blank\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2025\/12\/maxi-lidis.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Maxi Lids<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-6d14d937 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/aykasa.com\/es\/product\/tapas-midi-305-x-405\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2025\/12\/midi-lidis.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Midi Lids<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-8525bb03 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/aykasa.com\/es\/product\/mini-tapas-175-x-27\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2025\/12\/mini-lidis.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Mini Lids<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6d26b54f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-4eb7b264 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\"><strong>Sistema de Jarrones<\/strong><\/h2><\/div><p class=\"uagb-ifb-desc\">\u00a1Aykasa es el nuevo destino para tus flores! Con los jarrones de Aykasa podr\u00e1s mantener tus flores frescas y hermosas por m\u00e1s tiempo, aportando un toque est\u00e9tico a tus espacios. Para impresionar a tus clientes y brindarles una experiencia inolvidable, elige los jarrones de Aykasa.<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-5edb229e\">\n<div class=\"wp-block-uagb-info-box uagb-block-d8fd4580 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/aykasa.com\/es\/product\/jarron-base-midi-25x30x25\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_blank\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2024\/11\/430x519-vase-houseware-1.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-29fbd841 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><a href=\"https:\/\/aykasa.com\/es\/product\/jarron-grande-superior-31x-375x-382\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2024\/11\/430x519-vase-houseware-2.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-7bef9917 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/aykasa.com\/es\/product\/base-de-jarron-grande-33x-397x-382\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2024\/11\/430x519-vase-florists.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-39abff15 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\"><strong>Bolsos Plegables<\/strong><\/h2><\/div><p class=\"uagb-ifb-desc\">Sus elegantes dise\u00f1os completan tus conjuntos diarios y tambi\u00e9n son perfectos para ocasiones especiales. Cuando no est\u00e9s usando tu bolso, simplemente pli\u00e9galo para guardarlo ocupando el m\u00ednimo espacio. \u00a1Ideal para llevar de viaje o cuando sales de compras!<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-85422a35 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/aykasa.bitech.com.tr\/product\/foldable-mini-bag-20x10x26\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2025\/12\/mini-bag.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Mini Bolsa<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-info-box uagb-block-f24c815e uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/aykasa.bitech.com.tr\/product\/foldable-maxi-bag-38x22x52\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" src=\"https:\/\/aykasa.com\/wp-content\/uploads\/2025\/12\/maxi-bag.jpg\" alt=\"\" width=\"\" height=\"0\" loading=\"lazy\"\/><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Maxi Bolsa<\/p><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3202","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"rank_math_internal_links_processed":["1"],"site-post-title":["disabled"],"site-sidebar-layout":["no-sidebar"],"site-content-layout":["page-builder"],"ast-featured-img":["disabled"],"theme-transparent-header-meta":["default"],"ast-site-content-layout":["full-width-container"],"site-content-style":["unboxed"],"site-sidebar-style":["unboxed"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_last_translation_edit_mode":["native-editor"],"astra_style_timestamp_css":["1782811107"],"_edit_last":["1"],"_wp_page_template":[""],"_edit_lock":["1765867384:1"],"_uag_custom_page_level_css":[""],"astra-migrate-meta-layouts":["set"],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"footnotes":[""],"rank_math_seo_score":["19"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_wpml_word_count":["216"],"cmplz_hide_cookiebanner":[""],"_cmplz_scanned_post":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:141846:\".wp-block-uagb-container.uagb-block-d843ef95 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d843ef95 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d843ef95 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d843ef95 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d843ef95 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d843ef95{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d843ef95 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1400px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d843ef95{min-height: 788px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4fbe4bca .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4fbe4bca .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4fbe4bca .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4fbe4bca .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4fbe4bca .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4fbe4bca{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4fbe4bca > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4fbe4bca{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 0px;column-gap: 0px;}.uagb-block-6b3aacba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6b3aacba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-6b3aacba .uagb-ifb-icon svg{fill: #333;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6b3aacba .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6b3aacba .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6b3aacba .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6b3aacba .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6b3aacba .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6b3aacba .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6b3aacba .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-6b3aacba .uagb-ifb-title{color: var(--ast-global-color-1);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-6b3aacba .uagb-ifb-desc{color: #888888;margin-bottom: 46px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-6b3aacba .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-6b3aacba .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-6b3aacba .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-6b3aacba .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6b3aacba .uagb-infobox__content-wrap{text-align: center;}.uagb-block-6b3aacba.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6b3aacba .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-53b8e0b5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-53b8e0b5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-53b8e0b5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-53b8e0b5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-53b8e0b5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53b8e0b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53b8e0b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-53b8e0b5.uagb-layout-grid{row-gap: 50px;column-gap: 0px;grid-template-columns: minmax( 1px, 34%)  minmax( 1px, 34%)  minmax( 1px, 34%) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-53b8e0b5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;}.uagb-block-12c941e8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-12c941e8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-12c941e8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-12c941e8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-12c941e8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-12c941e8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-12c941e8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-12c941e8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-12c941e8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-12c941e8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-12c941e8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-12c941e8 .uagb-ifb-title{font-size: 15px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 10px;}.uagb-block-12c941e8 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-12c941e8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-12c941e8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-12c941e8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-12c941e8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-12c941e8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-12c941e8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-12c941e8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-12c941e8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-12c941e8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c4b23950 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c4b23950 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-c4b23950 .uagb-ifb-icon svg{fill: #333;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c4b23950 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-c4b23950 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c4b23950 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c4b23950 .uagb-ifb-title{font-size: 14px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 10px;}.uagb-block-c4b23950 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c4b23950 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c4b23950 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c4b23950 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c4b23950 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c4b23950 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-c4b23950.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-c4b23950.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-c4b23950.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c4b23950 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-a81b71dd .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a81b71dd .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-a81b71dd .uagb-ifb-icon svg{fill: #333;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a81b71dd .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a81b71dd .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a81b71dd .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a81b71dd .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-a81b71dd .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-a81b71dd .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-a81b71dd .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-a81b71dd .uagb-ifb-title{font-size: 14px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-a81b71dd .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-a81b71dd .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-a81b71dd .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-a81b71dd .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-a81b71dd .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a81b71dd .uagb-infobox__content-wrap{text-align: center;}.uagb-block-a81b71dd.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-a81b71dd.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a81b71dd .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-40367a60 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-40367a60 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-40367a60 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-40367a60 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-40367a60 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-40367a60{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-40367a60 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-40367a60{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: ;;row-gap: 0px;column-gap: 0px;}.uagb-block-31c1363d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-31c1363d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-31c1363d .uagb-ifb-icon svg{fill: #333;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-31c1363d .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-31c1363d .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-31c1363d .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-31c1363d .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-31c1363d .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-31c1363d .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-31c1363d .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-31c1363d .uagb-ifb-title{color: var(--ast-global-color-1);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-31c1363d .uagb-ifb-desc{color: #888888;margin-bottom: 46px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-31c1363d .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-31c1363d .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-31c1363d .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-31c1363d .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-31c1363d .uagb-infobox__content-wrap{text-align: center;}.uagb-block-31c1363d.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-31c1363d .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-e3d65400 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3d65400 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3d65400 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e3d65400 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e3d65400 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3d65400{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3d65400 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e3d65400.uagb-layout-grid{row-gap: 50px;column-gap: 0px;grid-template-columns: minmax( 1px, 34%)  minmax( 1px, 34%)  minmax( 1px, 34%) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-e3d65400{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;}.uagb-block-63831036 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-63831036 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-63831036 .uagb-ifb-icon svg{fill: #333;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-63831036 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-63831036 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-63831036 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-63831036 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-63831036 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-63831036 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-63831036.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-63831036 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-63831036 .uagb-ifb-title{font-size: 15px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 10px;}.uagb-block-63831036 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-63831036 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-63831036 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-63831036 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-63831036 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-63831036 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-63831036.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-63831036.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-63831036.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-63831036 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-63831036.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6d14d937 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6d14d937 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-6d14d937 .uagb-ifb-icon svg{fill: #333;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6d14d937 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6d14d937 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-6d14d937 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-6d14d937 .uagb-ifb-title{font-size: 14px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 10px;}.uagb-block-6d14d937 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-6d14d937 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-6d14d937 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-6d14d937 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-6d14d937 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6d14d937 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-6d14d937.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-6d14d937.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-6d14d937.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6d14d937 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8525bb03 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8525bb03 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-8525bb03 .uagb-ifb-icon svg{fill: #333;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8525bb03 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8525bb03 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8525bb03 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8525bb03 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-8525bb03 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8525bb03 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-8525bb03.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8525bb03 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-8525bb03 .uagb-ifb-title{font-size: 14px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8525bb03 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8525bb03 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-8525bb03 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-8525bb03 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8525bb03 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8525bb03 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-8525bb03.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-8525bb03.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-8525bb03.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8525bb03 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-6d26b54f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6d26b54f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6d26b54f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6d26b54f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6d26b54f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6d26b54f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6d26b54f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6d26b54f{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 0px;}.uagb-block-4eb7b264 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4eb7b264 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-4eb7b264 .uagb-ifb-icon svg{fill: #333;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4eb7b264 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4eb7b264 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4eb7b264 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4eb7b264 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4eb7b264 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4eb7b264 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4eb7b264 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-4eb7b264 .uagb-ifb-title{color: var(--ast-global-color-1);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-4eb7b264 .uagb-ifb-desc{color: #888888;margin-bottom: 46px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-4eb7b264 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-4eb7b264 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-4eb7b264 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-4eb7b264 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4eb7b264 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-4eb7b264.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4eb7b264 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-5edb229e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5edb229e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5edb229e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5edb229e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5edb229e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5edb229e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5edb229e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5edb229e.uagb-layout-grid{row-gap: 50px;column-gap: 0px;grid-template-columns: minmax( 1px, 34%)  minmax( 1px, 34%)  minmax( 1px, 34%) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5edb229e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;}.uagb-block-d8fd4580 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d8fd4580 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-d8fd4580 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d8fd4580 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d8fd4580 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d8fd4580 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d8fd4580 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-d8fd4580 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d8fd4580 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d8fd4580 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-d8fd4580 .uagb-ifb-title{font-size: 15px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 10px;}.uagb-block-d8fd4580 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d8fd4580 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d8fd4580 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d8fd4580 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d8fd4580 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d8fd4580 .uagb-infobox__content-wrap{text-align: right;}.uagb-block-d8fd4580.uagb-infobox-icon-above-title{text-align: right;}.uagb-block-d8fd4580.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d8fd4580 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap{text-align: left;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox-icon-above-title{text-align: left;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-29fbd841 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-29fbd841 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-29fbd841 .uagb-ifb-icon svg{fill: #333;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-29fbd841 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-29fbd841 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-29fbd841 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-29fbd841 .uagb-ifb-title{font-size: 14px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 10px;}.uagb-block-29fbd841 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-29fbd841 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-29fbd841 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-29fbd841 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-29fbd841 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-29fbd841 .uagb-infobox__content-wrap{text-align: right;}.uagb-block-29fbd841.uagb-infobox-icon-above-title{text-align: right;}.uagb-block-29fbd841.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-29fbd841.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-29fbd841 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap{text-align: left;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox-icon-above-title{text-align: left;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-7bef9917 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7bef9917 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7bef9917 .uagb-ifb-icon svg{fill: #333;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7bef9917 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7bef9917 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7bef9917 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7bef9917 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7bef9917 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7bef9917 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-7bef9917.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7bef9917 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-7bef9917 .uagb-ifb-title{font-size: 14px;color: #9d9fa1;margin-bottom: 6px;margin-top: 0px;margin-left: 0px;margin-right: 95px;}.uagb-block-7bef9917 .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7bef9917 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7bef9917 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7bef9917 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-7bef9917 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7bef9917 .uagb-infobox__content-wrap{text-align: right;}.uagb-block-7bef9917.uagb-infobox-icon-above-title{text-align: right;}.uagb-block-7bef9917.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-7bef9917.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 4px;padding-bottom: 0px;padding-left: 4px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-7bef9917 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap{text-align: left;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox-icon-above-title{text-align: left;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-39abff15 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-39abff15 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-39abff15 .uagb-ifb-icon svg{fill: #333;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-39abff15 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-39abff15 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-39abff15 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-39abff15 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-39abff15 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-39abff15 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-39abff15 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-39abff15 .uagb-ifb-title{color: var(--ast-global-color-1);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-39abff15 .uagb-ifb-desc{color: #888888;margin-bottom: 46px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-39abff15 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-39abff15 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-39abff15 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-39abff15 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-39abff15 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-39abff15.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-39abff15 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-39abff15.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-85422a35 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-85422a35 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-85422a35 .uagb-ifb-icon svg{fill: #333;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85422a35 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85422a35 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85422a35 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85422a35 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-85422a35 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-85422a35 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-85422a35 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-85422a35 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-85422a35 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-85422a35 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-85422a35 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-85422a35 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-85422a35 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-85422a35 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-85422a35.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-85422a35 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-85422a35.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-f24c815e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f24c815e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-f24c815e .uagb-ifb-icon svg{fill: #333;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f24c815e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f24c815e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f24c815e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f24c815e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-f24c815e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-f24c815e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-f24c815e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-f24c815e .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-f24c815e .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-f24c815e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-f24c815e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-f24c815e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-f24c815e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f24c815e .uagb-infobox__content-wrap{text-align: center;}.uagb-block-f24c815e.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f24c815e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d843ef95{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d843ef95 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d843ef95{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4fbe4bca{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4fbe4bca > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;}.wp-block-uagb-container.uagb-block-4fbe4bca{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;row-gap: 0px;}.uagb-block-6b3aacba .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-6b3aacba .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6b3aacba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6b3aacba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6b3aacba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6b3aacba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 23px;margin-left: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53b8e0b5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53b8e0b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-53b8e0b5.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-53b8e0b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-12c941e8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-12c941e8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-12c941e8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-12c941e8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-12c941e8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-12c941e8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-12c941e8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c4b23950 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c4b23950 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c4b23950 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-c4b23950.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-c4b23950.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a81b71dd .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a81b71dd .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a81b71dd .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a81b71dd .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-40367a60{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-40367a60 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;}.wp-block-uagb-container.uagb-block-40367a60{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: ;;row-gap: 0px;}.uagb-block-31c1363d .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-31c1363d .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-31c1363d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-31c1363d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-31c1363d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-31c1363d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-31c1363d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-31c1363d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 23px;margin-left: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3d65400{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3d65400 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e3d65400.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-e3d65400{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-63831036 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-63831036 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-63831036 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-63831036 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-63831036 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-63831036.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-63831036.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6d14d937 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6d14d937 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6d14d937 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6d14d937.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-6d14d937.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8525bb03 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8525bb03 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8525bb03 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8525bb03 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8525bb03 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8525bb03.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-8525bb03.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6d26b54f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6d26b54f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;}.wp-block-uagb-container.uagb-block-6d26b54f{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 0px;}.uagb-block-4eb7b264 .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-4eb7b264 .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4eb7b264 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4eb7b264 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4eb7b264 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4eb7b264 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 23px;margin-left: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5edb229e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5edb229e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5edb229e.uagb-layout-grid{grid-template-columns: minmax( 1px, 1fr)  minmax( 1px, 1fr)  minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5edb229e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d8fd4580 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d8fd4580 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d8fd4580 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d8fd4580 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-29fbd841 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-29fbd841 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-29fbd841 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-29fbd841.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-29fbd841.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7bef9917 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7bef9917 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7bef9917 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7bef9917 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7bef9917 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7bef9917.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-7bef9917.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-39abff15 .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-39abff15 .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 100px;margin-right: 100px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-39abff15 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-39abff15 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-39abff15 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-39abff15 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-39abff15 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-39abff15.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 23px;margin-left: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-85422a35 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-85422a35 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-85422a35 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-85422a35 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85422a35 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f24c815e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f24c815e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f24c815e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f24c815e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f24c815e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-d843ef95{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d843ef95 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d843ef95{min-height: 223px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4fbe4bca{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4fbe4bca > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-4fbe4bca{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;order: initial;background-color: ;;}.uagb-block-6b3aacba .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-6b3aacba .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6b3aacba .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6b3aacba .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6b3aacba .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6b3aacba.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-53b8e0b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-53b8e0b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-53b8e0b5.uagb-layout-grid{row-gap: 40px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-53b8e0b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-12c941e8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-12c941e8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-12c941e8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-12c941e8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-12c941e8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-12c941e8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-12c941e8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-12c941e8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-12c941e8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-c4b23950 .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 63px;margin-right: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c4b23950 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-c4b23950 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-c4b23950 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c4b23950.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-c4b23950.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-c4b23950.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-c4b23950.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-a81b71dd .uagb-ifb-title{margin-left: 91px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-a81b71dd .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-a81b71dd .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-a81b71dd .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-a81b71dd.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-a81b71dd.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-a81b71dd.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-40367a60{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-40367a60 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-40367a60{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;order: initial;background-color: ;;}.uagb-block-31c1363d .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-31c1363d .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-31c1363d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-31c1363d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-31c1363d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-31c1363d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-31c1363d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-31c1363d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e3d65400{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e3d65400 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e3d65400.uagb-layout-grid{row-gap: 40px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-e3d65400{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-63831036 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-63831036 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-63831036 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-63831036 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-63831036 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-63831036.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-63831036.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-63831036.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-63831036.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-63831036.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-63831036.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-6d14d937 .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 63px;margin-right: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6d14d937 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6d14d937 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6d14d937 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6d14d937.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-6d14d937.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-6d14d937.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-6d14d937.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-8525bb03 .uagb-ifb-title{margin-left: 91px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-8525bb03 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8525bb03 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8525bb03 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-8525bb03 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-8525bb03 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-8525bb03.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-8525bb03.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-8525bb03.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-8525bb03.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6d26b54f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6d26b54f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;}.wp-block-uagb-container.uagb-block-6d26b54f{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top:  !important;margin-bottom:  !important;row-gap: 0px;order: initial;}.uagb-block-4eb7b264 .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-4eb7b264 .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4eb7b264 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4eb7b264 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4eb7b264 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-4eb7b264.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5edb229e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5edb229e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5edb229e.uagb-layout-grid{row-gap: 40px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-5edb229e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 50px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d8fd4580 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-d8fd4580 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-d8fd4580 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-d8fd4580.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d8fd4580.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d8fd4580.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-29fbd841 .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 63px;margin-right: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-29fbd841 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-29fbd841 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-29fbd841 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-29fbd841.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-29fbd841.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-29fbd841.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841 .uagb-ifb-content > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-left-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841 .uagb-ifb-content .uagb-ifb-right-title-image > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-29fbd841.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-7bef9917 .uagb-ifb-title{margin-left: 91px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7bef9917 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7bef9917 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7bef9917 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7bef9917 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7bef9917 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7bef9917.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-7bef9917.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-7bef9917.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-7bef9917.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-39abff15 .uagb-ifb-title{margin-bottom: 20px;}.uagb-block-39abff15 .uagb-ifb-desc{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-39abff15 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-39abff15 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-39abff15 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-39abff15 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-39abff15 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-39abff15.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-39abff15.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-85422a35 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85422a35 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-85422a35 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-85422a35 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-85422a35 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-85422a35.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-85422a35.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-f24c815e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f24c815e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-f24c815e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-f24c815e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-f24c815e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-f24c815e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:15:{i:0;s:14:\"uagb\/container\";i:1;s:9:\"core\/html\";i:3;s:13:\"uagb\/info-box\";i:4;s:12:\"core\/columns\";i:5;s:11:\"core\/column\";i:6;s:14:\"core\/paragraph\";i:7;s:11:\"core\/search\";i:8;s:10:\"core\/group\";i:9;s:12:\"core\/heading\";i:10;s:17:\"core\/latest-posts\";i:11;s:20:\"core\/latest-comments\";i:12;s:13:\"core\/archives\";i:13;s:15:\"core\/categories\";i:14;s:30:\"woocommerce\/product-categories\";i:15;s:18:\"core\/legacy-widget\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1783975504\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"Murat B","author_link":"https:\/\/aykasa.com\/es\/author\/bitekyazilim\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/pages\/3202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/comments?post=3202"}],"version-history":[{"count":10,"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/pages\/3202\/revisions"}],"predecessor-version":[{"id":3810,"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/pages\/3202\/revisions\/3810"}],"wp:attachment":[{"href":"https:\/\/aykasa.com\/es\/wp-json\/wp\/v2\/media?parent=3202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}